{"id":172200,"date":"2026-02-11T14:29:45","date_gmt":"2026-02-11T13:29:45","guid":{"rendered":"https:\/\/www.divertisenvivo.com\/?page_id=172200"},"modified":"2026-02-11T15:06:39","modified_gmt":"2026-02-11T14:06:39","slug":"mundial-2026","status":"publish","type":"page","link":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/","title":{"rendered":"Mundial 2026"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"172200\" class=\"elementor elementor-172200\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3777626 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3777626\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d992bc elementor-widget elementor-widget-image\" data-id=\"4d992bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.divertisenvivo.com\/wp-content\/uploads\/2026\/02\/Mundial-de-futbol-2026-1920-x-800-px.png?fit=1920%2C800&#038;ssl=1\" title=\"Mundial 2026\" alt=\"Mundial 2026\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ee349f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6ee349f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34baba3 elementor-widget elementor-widget-spacer\" data-id=\"34baba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5703e81 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5703e81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb643fa elementor-widget elementor-widget-heading\" data-id=\"eb643fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mundial 2026 - Viajes a USA, M\u00e9xico y Canada<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8cb8746 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"8cb8746\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ee95d8 elementor-widget elementor-widget-text-editor\" data-id=\"9ee95d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Mundial de F\u00fatbol 2026 se disputar\u00e1 en 3 pa\u00edses como son USA, M\u00e9xico y Canada.\u00a0<\/p><p>En Divertis en Vivo somos especialistas en turismo deportivo desde 2007 y ponemos a vuestra disposici\u00f3n nuestros servicios para disfrutar de una cita hist\u00f3rica. Si est\u00e1s buscando conexiones de vuelos, alojamiento, traslados, entradas generales o una experiencia VIP para tu viaje de incentivo consulta nuestras opciones y garantiza tu presencia en el Mundial 2026.<\/p><p><span style=\"font-weight: 400;\">Conf\u00eda en nuestra experiencia como agencia especializada en viajes deportivos. Cont\u00e1ctanos en <\/span><a href=\"mailto:vgarcia@divertisenvivo.com\"><b>vgarcia@divertisenvivo.com<\/b><\/a><span style=\"font-weight: 400;\"> o rellena nuestro formulario para que preparemos tu propuesta personalizada.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1ffd89 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e1ffd89\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d71bcbd elementor-widget elementor-widget-heading\" data-id=\"d71bcbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qu\u00e9 ofrecemos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a440634 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a440634\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90e338b elementor-widget elementor-widget-text-editor\" data-id=\"90e338b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"2033\" data-end=\"2107\"><p data-start=\"2035\" data-end=\"2107\"><strong data-start=\"2035\" data-end=\"2070\">Entradas oficiales garantizadas<\/strong> en distintos sectores del estadio. Entradas generales y opciones VIP\/Hospitality.<\/p><\/li><li data-start=\"2108\" data-end=\"2190\"><p data-start=\"2110\" data-end=\"2190\"><strong data-start=\"2110\" data-end=\"2135\">Hoteles en las ciudades.<\/strong><\/p><\/li><li data-start=\"2191\" data-end=\"2271\"><p data-start=\"2193\" data-end=\"2271\"><strong data-start=\"2193\" data-end=\"2215\">Opciones flexibles<\/strong>: solo entrada + hotel o pack completo con transporte.<\/p><\/li><li data-start=\"2272\" data-end=\"2341\"><p data-start=\"2274\" data-end=\"2341\"><strong data-start=\"2274\" data-end=\"2292\">Ambiente \u00fanico<\/strong>: c\u00e1nticos, pasi\u00f3n y el mejor f\u00fatbol del mundo.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-645fc212 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"645fc212\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-107631fd elementor-widget elementor-widget-heading\" data-id=\"107631fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nSolicita tu Presupuesto para tu viaje al Mundial 2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-481ecf3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"481ecf3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5cfd52 elementor-widget elementor-widget-shortcode\" data-id=\"f5cfd52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"everest-forms\"><div class=\"evf-container default\" id=\"evf-169945\"><form id=\"evf-form-169945\" class=\"everest-form\" data-formid=\"169945\" data-ajax_submission=\"0\" data-keyboard_friendly_form=\"0\" data-form_state_type=\"\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/eu\/wp-json\/wp\/v2\/pages\/172200\"><div class=\"evf-field-container\"><input type=\"hidden\" id=\"_wpnonce169945\" name=\"_wpnonce169945\" value=\"8e159cc000\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/eu\/wp-json\/wp\/v2\/pages\/172200\" \/><div class=\"evf-frontend-row\" data-row=\"row_1\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-169945-field_ys0GeZISRs-1-container\" class=\"evf-field evf-field-first-name form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"ys0GeZISRs-1\"><label class=\"evf-field-label\" for=\"evf-169945-field_ys0GeZISRs-1\"><span class=\"evf-label\">Nombre<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"text\" id=\"evf-169945-field_ys0GeZISRs-1\" class=\"input-text\" name=\"everest_forms[form_fields][ys0GeZISRs-1]\" required><\/div><div id=\"evf-169945-field_LbH5NxasXM-2-container\" class=\"evf-field evf-field-email form-row validate-required validate-email\" data-required-field-message=\"Please enter a valid email address.\" data-field-id=\"LbH5NxasXM-2\"><label class=\"evf-field-label\" for=\"evf-169945-field_LbH5NxasXM-2\"><span class=\"evf-label\">Email<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"email\" id=\"evf-169945-field_LbH5NxasXM-2\" class=\"input-text\" name=\"everest_forms[form_fields][LbH5NxasXM-2]\" required ><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_2\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-169945-field_vWHegkc2Nl-5-container\" class=\"evf-field evf-field-radio form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"vWHegkc2Nl-5\"><label class=\"evf-field-label\" for=\"evf-169945-field_vWHegkc2Nl-5\"><span class=\"evf-label\">Pack de inter\u00e9s (marca los que quieras)<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><ul id=\"evf-169945-field_vWHegkc2Nl-5\" class=\" evf-field-required\"><li class=\"choice-1 depth-1\"><input type=\"radio\" id=\"evf-169945-field_vWHegkc2Nl-5_1\" class=\"input-text\" name=\"everest_forms[form_fields][vWHegkc2Nl-5]\" value=\"Pack A \u2014 Hotel + entradas\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_vWHegkc2Nl-5_1\">Pack A \u2014 Hotel + entradas<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"radio\" id=\"evf-169945-field_vWHegkc2Nl-5_2\" class=\"input-text\" name=\"everest_forms[form_fields][vWHegkc2Nl-5]\" value=\"Pack B \u2014 Vuelo + hotel + entradas\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_vWHegkc2Nl-5_2\">Pack B \u2014 Vuelo + hotel + entradas<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"radio\" id=\"evf-169945-field_vWHegkc2Nl-5_3\" class=\"input-text\" name=\"everest_forms[form_fields][vWHegkc2Nl-5]\" value=\"Pack C \u2014 Experiencia Deluxe (vuelos+traslados+hotel+entradas+extras)\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_vWHegkc2Nl-5_3\">Pack C \u2014 Experiencia Deluxe (vuelos+traslados+hotel+entradas+extras)<\/label><\/li><\/ul><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_3\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-169945-field_cIz9SU4YOh-6-container\" class=\"evf-field evf-field-checkbox form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"cIz9SU4YOh-6\"><label class=\"evf-field-label\" for=\"evf-169945-field_cIz9SU4YOh-6\"><span class=\"evf-label\">Ciudad preferida<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><ul id=\"evf-169945-field_cIz9SU4YOh-6\" class=\" evf-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"evf-169945-field_cIz9SU4YOh-6_1\" class=\"input-text\" name=\"everest_forms[form_fields][cIz9SU4YOh-6][]\" value=\"Ciudad de M\u00e9xico \u2013 Estadio Azteca\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_cIz9SU4YOh-6_1\">Ciudad de M\u00e9xico \u2013 Estadio Azteca<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"evf-169945-field_cIz9SU4YOh-6_2\" class=\"input-text\" name=\"everest_forms[form_fields][cIz9SU4YOh-6][]\" value=\"New York\/New Jersey\u2013 MetLife Stadium\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_cIz9SU4YOh-6_2\">New York\/New Jersey\u2013 MetLife Stadium<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"evf-169945-field_cIz9SU4YOh-6_3\" class=\"input-text\" name=\"everest_forms[form_fields][cIz9SU4YOh-6][]\" value=\"Dallas \u2013 AT&amp;T Stadium\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_cIz9SU4YOh-6_3\">Dallas \u2013 AT&amp;T Stadium<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"evf-169945-field_cIz9SU4YOh-6_4\" class=\"input-text\" name=\"everest_forms[form_fields][cIz9SU4YOh-6][]\" value=\"Atlanta \u2013 Mercedes-Benz Stadium\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_cIz9SU4YOh-6_4\">Atlanta \u2013 Mercedes-Benz Stadium<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"evf-169945-field_cIz9SU4YOh-6_5\" class=\"input-text\" name=\"everest_forms[form_fields][cIz9SU4YOh-6][]\" value=\"Toronto \u2013 BMO Field\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_cIz9SU4YOh-6_5\">Toronto \u2013 BMO Field<\/label><\/li><li class=\"choice-6 depth-1\"><input type=\"checkbox\" id=\"evf-169945-field_cIz9SU4YOh-6_6\" class=\"input-text\" name=\"everest_forms[form_fields][cIz9SU4YOh-6][]\" value=\"Vancouver \u2013 BC Place\" required ><label class=\"everest-forms-field-label-inline\" for=\"evf-169945-field_cIz9SU4YOh-6_6\">Vancouver \u2013 BC Place<\/label><\/li><\/ul><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_4\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-169945-field_F9O44oHkUo-7-container\" class=\"evf-field evf-field-text form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"F9O44oHkUo-7\"><label class=\"evf-field-label\" for=\"evf-169945-field_F9O44oHkUo-7\"><span class=\"evf-label\">N\u00famero de viajeros<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"text\" id=\"evf-169945-field_F9O44oHkUo-7\" class=\"input-text\" name=\"everest_forms[form_fields][F9O44oHkUo-7]\" required><\/div><div id=\"evf-169945-field_RdFDRE25jW-8-container\" class=\"evf-field evf-field-text form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"RdFDRE25jW-8\"><label class=\"evf-field-label\" for=\"evf-169945-field_RdFDRE25jW-8\"><span class=\"evf-label\">N\u00famero de noches<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"text\" id=\"evf-169945-field_RdFDRE25jW-8\" class=\"input-text\" name=\"everest_forms[form_fields][RdFDRE25jW-8]\" required><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_5\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-169945-field_YJU3lFP52t-9-container\" class=\"evf-field evf-field-text form-row\" data-field-id=\"YJU3lFP52t-9\"><label class=\"evf-field-label\" for=\"evf-169945-field_YJU3lFP52t-9\"><span class=\"evf-label\">Comentarios<\/span> <\/label><input type=\"text\" id=\"evf-169945-field_YJU3lFP52t-9\" class=\"input-text\" name=\"everest_forms[form_fields][YJU3lFP52t-9]\" ><div class=\"evf-field-description\">Extras, traslados, excursiones,... Cuanta m\u00e1s informaci\u00f3n nos proporciones m\u00e1s detallada ser\u00e1 tu propuesta.<\/div><\/div><\/div><\/div><div class=\"evf-frontend-row\" data-row=\"row_6\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-169945-field_rmbGagNiHr-10-container\" class=\"evf-field evf-field-privacy-policy form-row validate-required\" data-required-field-message=\"This field is required.\" data-field-id=\"rmbGagNiHr-10\"><label class=\"evf-field-label\" for=\"evf-169945-field_rmbGagNiHr-10\"><span class=\"evf-label\">Politica de privacidad<\/span> <abbr class=\"required\" title=\"Required\">*<\/abbr><\/label><input type=\"checkbox\" value=\"He le\u00eddo y acepto la [Pol\u00edtica de privacidad](?page_id=1705)\" id=\"evf-169945-field_rmbGagNiHr-10\" class=\"input-text\" name=\"everest_forms[form_fields][rmbGagNiHr-10]\" required \/><label class=\"evf-privacy-policy-consent-message\" for=\"evf-169945-field_rmbGagNiHr-10\">He le\u00eddo y acepto la <a data-page-id=\"1705\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.divertisenvivo.com\/eu\/politica-de-privacidad\/\" class=\" evf-privacy-policy-local-page-link\">Pol\u00edtica de privacidad<\/a><\/label><div class=\"evf-privacy-policy-local-page-contents\"><div class=\"evf-privacy-policy-local-page-content evf-privacy-policy-local-page-content-1705\" hidden><h1>Pol\u00edtica de Privacidad (Informaci\u00f3n y Consentimiento)<\/h1>\r\n<table width=\"100%\" cellspacing=\"1\" cellpadding=\"10\">\r\n<tbody>\r\n<tr>\r\n<td colspan=\"2\" bgcolor=\"#cccccc\" width=\"100%\"><strong>Informaci\u00f3n b\u00e1sica sobre protecci\u00f3n de datos<\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"18%\">Responsable:<\/td>\r\n<td width=\"82%\">\r\n<p align=\"justify\"><strong>QUIERES VIAJAR SL<\/strong><\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"18%\">Finalidad:<\/td>\r\n<td width=\"82%\">\r\n<p align=\"justify\">Prestar los servicios solicitados y atender sus\u00a0solicitudes de contacto a trav\u00e9s de nuestros\u00a0formularios de la p\u00e1gina web:\u00a0https:\/\/www.divertisenvivo.com\/ as\u00ed como el env\u00edo\u00a0de comunicaciones comerciales y newsletter\u00a0informativo.<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"18%\">Legitimaci\u00f3n:<\/td>\r\n<td width=\"82%\">\r\n<ul>\r\n \t<li>\r\n<p align=\"justify\">Ejecuci\u00f3n de un contrato.<\/p>\r\n<\/li>\r\n \t<li>\r\n<p align=\"justify\">Consentimiento del interesado.<\/p>\r\n<\/li>\r\n \t<li>\r\n<p align=\"justify\">Cumplimiento de obligaciones legales<\/p>\r\n<\/li>\r\n \t<li>\r\n<p align=\"justify\">Inter\u00e9s leg\u00edtimo del responsable o de terceros responsables<\/p>\r\n<\/li>\r\n<\/ul>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"18%\">Destinatarios:<\/td>\r\n<td width=\"82%\">\r\n<p align=\"justify\">No se ceder\u00e1n datos a terceros, salvo obligaci\u00f3n\u00a0legal.<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"18%\">Derechos:<\/td>\r\n<td width=\"82%\">\r\n<p align=\"justify\">Tiene derecho a acceder, rectificar y suprimir los datos, as\u00ed como otros derechos, indicados en la informaci\u00f3n adicional, que puede ejercer enviando correo electr\u00f3nico a\u00a0info@divertisenvivo.com\u00a0o dirigi\u00e9ndose a nuestras instalaciones.<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"18%\">Procedencia:<\/td>\r\n<td width=\"82%\">\r\n<p align=\"justify\">Del propio interesado y de nuestra p\u00e1gina web\u00a0https:\/\/www.divertisenvivo.com\/<\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"18%\">Informaci\u00f3n adicional:<\/td>\r\n<td width=\"82%\">Puede consultar informaci\u00f3n adicional y detallada sobre Protecci\u00f3n de Datos en nuestra p\u00e1gina web:\u00a0https:\/\/www.divertisenvivo.com\/<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<p align=\"justify\">En caso de que nuestra pol\u00edtica de protecci\u00f3n de datos tuviera que variar a consecuencia de cambios legislativos o de criterios emanados de la Agencia de Protecci\u00f3n de Datos ser\u00eda convenientemente informado de cualquier variaci\u00f3n que fuere necesaria introducir para cumplir con la ley<\/p>\r\n<p align=\"justify\">En QUIERES VIAJAR SL trabajamos para ofrecerte a trav\u00e9s de nuestros productos y servicios la mejor experiencia posible. En algunos casos, es necesario recabar informaci\u00f3n para conseguirlo. Nos importa tu privacidad y creemos que debemos ser transparentes al respecto.<\/p>\r\nPor ello, y a efectos de lo previsto en el REGLAMENTO (UE) 2016\/679 DEL PARLAMENTO\u00a0EUROPEO Y DEL CONSEJO de 27 de abril de 2016 (en adelante, \u201cRGPD\u201d) y la ley LOPG\u00a0GDD 3\/2018 relativos a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento\u00a0de datos personales y a la libre circulaci\u00f3n de estos datos, y lay la LEY 34\/2002, de 11 de julio,\u00a0de Servicios de la Sociedad de la informaci\u00f3n y de comercio electr\u00f3nico (en adelante, \u201cLSSI\u201d),\u00a0QUIERES VIAJAR SL informa al usuario que, como responsable del tratamiento, incorporar\u00e1\u00a0los datos de car\u00e1cter personal facilitados por los usuarios a los sistemas de tratamiento\u00a0automatizados de la organizaci\u00f3n.\r\nNuestro compromiso empieza por explicarte lo siguiente:\r\n\u2022 Se recogen tus datos para que la experiencia de usuario mejore, atendiendo a tus\u00a0intereses y necesidades.\r\n\u2022 Somos transparentes en relaci\u00f3n a los datos que obtenemos acerca de ti y la raz\u00f3n por\u00a0la que lo hacemos.\r\n\r\nNuestra intenci\u00f3n es ofrecerte la mejor experiencia posible. Por ello, cuando vayamos a usar tu\u00a0informaci\u00f3n personal lo haremos siempre cumpliendo la normativa, y cuando sea necesario,\u00a0solicitaremos tu consentimiento.\r\n\u2022 Entendemos que tus datos te pertenecen. Por tanto, si decides no autorizarnos a\r\nprocesarlos puedes solicitarnos que dejemos de tratarlos.\r\n\u2022 Nuestra prioridad consiste en garantizar tu seguridad y tratar tus datos de acuerdo con\r\nla normativa europea.\r\nSi deseas obtener m\u00e1s informaci\u00f3n sobre el tratamiento de tus datos, consulta los distintos\u00a0apartados de la pol\u00edtica de privacidad que se encuentran a continuaci\u00f3n:\r\n<h2 align=\"justify\">\u00bfQui\u00e9n es el responsable del tratamiento de sus datos?<\/h2>\r\n<strong>Identidad<\/strong>: QUIERES VIAJAR SL\u00a0<b>NIF<\/b>: B31899685\r\n<strong>Direcci\u00f3n postal<\/strong>: CALLE URBANIZACION ITAROA 2 (Centro empresarial Itaroa), 31620 \u2013 Gorraiz (Navarra)\r\n<strong>Tel\u00e9fono<\/strong>: 848 98 20 00\r\n\r\n<strong>Correo electr\u00f3nico<\/strong>:<a href=\"mailto:info@divertisenvivo.com\">\u00a0info@divertisenvivo.com<\/a>\r\n<h2 align=\"justify\">\u00bfCon qu\u00e9 finalidad tratamos sus datos personales?<\/h2>\r\nEn QUIERES VIAJAR SL Tratamos la informaci\u00f3n que nos facilitan las personas interesadas\u00a0con el fin de prestar los servicios solicitados y atender sus solicitudes de contacto a trav\u00e9s de\r\nnuestros formularios de la p\u00e1gina web https:\/\/www.divertisenvivo.com\/. Desarrollar y gestionar\u00a0los concursos, sorteos u otras actividades promocionales que se puedan organizar.\u00a0As\u00ed como el env\u00edo de comunicaciones comerciales y newsletter informativo. as\u00ed como el env\u00edo\u00a0de nuestra newsletter y comunicaciones comerciales, inclusive por correo electr\u00f3nico, sobre\u00a0nuestros productos y servicios.\r\nEn algunos casos ser\u00e1 necesario facilitar informaci\u00f3n a las Autoridades o terceras empresas\u00a0por motivos de auditor\u00eda, as\u00ed como manejar datos personales de facturas, contratos y\u00a0documentos para responder a reclamaciones de clientes o de las Administraciones P\u00fablicas.\r\nInformamos que los datos personales que se obtengan como consecuencia de tu registro como\u00a0usuario formar\u00e1n parte del Registro de Actividades y operaciones de Tratamiento (RAT), que\u00a0se actualizar\u00e1 peri\u00f3dicamente de acuerdo con lo establecido en el RGPD.\r\n<p align=\"justify\">\u00bfPor cu\u00e1nto tiempo conservaremos sus datos?<\/p>\r\n<p align=\"justify\">Los datos se conservar\u00e1n mientras no solicite su supresi\u00f3n.<\/p>\r\n<p align=\"justify\">\u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de sus datos?<\/p>\r\n<p align=\"justify\">Le indicamos la base legal para el tratamiento de sus datos:<\/p>\r\n\r\n<ul>\r\n \t<li>\r\n<p align=\"justify\"><strong>Ejecuci\u00f3n de un contrato<\/strong>: Ejecuci\u00f3n de un contrato de compra\/venta o suministro sobre nuestros productos y\/o servicios, incluso por medio de nuestra venta online<\/p>\r\n<\/li>\r\n \t<li>\r\n<p align=\"justify\"><strong>Consentimiento del interesado<\/strong>: El env\u00edo de comunicaciones comerciales de nuestros productos y servicios. La suscripci\u00f3n a nuestros boletines \u201cnewsletter\u201d, el acceso y tratamiento de sus datos para la gesti\u00f3n de nuestra \u00e1rea privada, programas de fidelizaci\u00f3n de clientes para el uso por parte del usuario de bonos y descuentos, usuario con su registro en la tienda online para el uso de los servicios de la tienda online https:\/\/www.divertisenvivo.com\/\/ La publicaci\u00f3n de im\u00e1genes y videos en la p\u00e1gina web, redes sociales corporativas, revistas, tr\u00edpticos, cat\u00e1logos de productos, incluidos el tratamiento de datos de menores con el consentimiento expreso del padre\/madre y\/o Tutor legal.<\/p>\r\n<\/li>\r\n \t<li>\r\n<p align=\"justify\"><b>Inter\u00e9s leg\u00edtimo del responsable<\/b>: Finalidades relacionadas con la prestaci\u00f3n, asistencia y comunicaci\u00f3n sobre los servicios o productos contratados. Gesti\u00f3n administrativa, contable y fiscal; compra, atenci\u00f3n al cliente, devoluci\u00f3n, cesi\u00f3n a terceros para el transporte y entrega, gestiones de cupones y ofertas a clientes, comunicaciones con el cliente en relaci\u00f3n al servicio, reclamaciones y quejas. Comunicaciones con el cliente; la cesi\u00f3n de datos a terceras empresas relacionadas con el Responsable del Tratamiento con la finalidad de tratamientos relacionados con este inter\u00e9s leg\u00edtimo.<\/p>\r\n<\/li>\r\n \t<li>Cumplimiento de obligaciones legales para prevenci\u00f3n del fraude, comunicaci\u00f3n con Autoridades p\u00fablicas y reclamaciones de terceros.<\/li>\r\n<\/ul>\r\n<p align=\"justify\">\u00bfA qu\u00e9 destinatarios se comunicar\u00e1n sus datos?<\/p>\r\n<p align=\"justify\">En algunos casos, solo cuando sea necesario, QUIERES VIAJAR SL proporcionar\u00e1 datos de los usuarios a terceros. Sin embargo, nunca se vender\u00e1n los datos a terceros. Los proveedores de servicios externos (por ejemplo, proveedores de pago o empresas de reparto) con los que QUIERES VIAJAR SL trabaje pueden usar los datos para proporcionar los servicios correspondientes, sin embargo no usar\u00e1n dicha informaci\u00f3n para fines propios o para cesi\u00f3n a terceros.\r\nQUIERES VIAJAR SL procura garantizar la seguridad de los datos personales cuando se env\u00edan fuera de la empresa y se asegura que los terceros proveedores de servicio respetan la confidencialidad y cuentan con las medidas adecuadas para proteger los datos personales.\r\nDichos terceros tienen la obligaci\u00f3n de garantizar que la informaci\u00f3n se trata conforme con la normativa de privacidad de datos.\r\nEn algunos casos, la ley puede exigir que se revelen datos personales a organismos p\u00fablicos u otras partes, solo se revelar\u00e1 lo estrictamente necesario para el cumplimiento de dichas obligaciones legales.\r\nLos datos personales obtenidos tambi\u00e9n podr\u00e1n ser compartidos con otras empresas del grupo.<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfTransferencias de datos a terceros pa\u00edses?<\/h2>\r\n<p align=\"justify\">No est\u00e1n previstas transferencias de datos a terceros pa\u00edses.<\/p>\r\n<p align=\"justify\">\u00bfQu\u00e9 datos personales recopilamos?<\/p>\r\n<p align=\"justify\">Los datos personales que el usuario puede llegar a proporcionar:<\/p>\r\n<p align=\"justify\">\u2022\u00a0Nombre, direcci\u00f3n y fecha de nacimiento.<\/p>\r\n<p align=\"justify\">\u2022\u00a0N\u00famero de tel\u00e9fono y direcci\u00f3n de correo electr\u00f3nico.<\/p>\r\n<p align=\"justify\">\u2022\u00a0Ubicaci\u00f3n.<\/p>\r\n<p align=\"justify\">\u2022\u00a0Informaci\u00f3n relativa a pagos y devoluciones. Datos bancarios.<\/p>\r\n<p align=\"justify\">\u2022\u00a0Direcci\u00f3n IP, fecha y hora en la que has accedido a nuestros servicios, navegador de internet que uses y datos sobre el sistema operativo del dispositivo.<\/p>\r\n<p align=\"justify\">Cualquier otra informaci\u00f3n o datos que decidas compartir con nosotros.<\/p>\r\n<p align=\"justify\">En algunos casos, es obligatoria la cumplimentaci\u00f3n del formulario de registro para acceder y disfrutar de determinados servicios ofrecidos en la web; asimismo, no facilitar los datos personales solicitados o el no aceptar la presente pol\u00edtica de protecci\u00f3n de datos supone la imposibilidad de suscribirse, registrarse o participar en cualquiera de las promociones en las que se soliciten datos car\u00e1cter personal.<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfD\u00f3nde se almacenan tus datos?<\/h2>\r\n<p align=\"justify\">Con car\u00e1cter general, los datos se almacenan dentro de la UE. Los datos que se env\u00eden a terceros que no pertenezcan a la UE, nos aseguraremos que ofrezcan un nivel de protecci\u00f3n suficiente, ya sea porque cuentan con Normas Corporativas Vinculantes (BCR) o porque se hayan adherido al \u201cPrivacyShield\u201d.<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfCu\u00e1les son sus derechos cuando nos facilita sus datos?<\/h2>\r\n<p align=\"justify\">Cualquier persona tiene derecho a obtener confirmaci\u00f3n sobre si QUIERES VIAJAR SL est\u00e1 tratando datos personales que les conciernan, o no.<\/p>\r\n<p align=\"justify\">Las personas interesadas tienen derecho a acceder a sus datos personales, as\u00ed como a solicitar la rectificaci\u00f3n de los datos inexactos o, en su caso, solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sean necesarios para los fines que fueron recogidos.<\/p>\r\n<p align=\"justify\">En determinadas circunstancias, los interesados podr\u00e1n solicitar la limitaci\u00f3n del tratamiento de sus datos, en cuyo caso \u00fanicamente los conservaremos para el ejercicio o la defensa de reclamaciones.<\/p>\r\n<p align=\"justify\">En determinadas circunstancias y por motivos relacionados con su situaci\u00f3n particular, los interesados podr\u00e1n oponerse al tratamiento de sus datos. En este caso, QUIERES VIAJAR SL dejar\u00e1 de tratar los datos, salvo por motivos leg\u00edtimos imperiosos, o el ejercicio o la defensa de posibles reclamaciones.<\/p>\r\n<p align=\"justify\">Podr\u00e1 ejercitar materialmente sus derechos de la siguiente forma: Tiene derecho a acceder, rectificar y suprimir los datos, as\u00ed como otros derechos, indicados en la informaci\u00f3n adicional, que puede ejercer enviando correo electr\u00f3nico a\u00a0info@divertisenvivo.com\u00a0o directamente en la direcci\u00f3n: CALLE URBANIZACION ITAROA 2 (Centro empresarial Itaroa), 31620 \u2013 Gorraiz (Navarra)<\/p>\r\n<p align=\"justify\">Si ha otorgado su consentimiento para alguna finalidad concreta, tiene derecho a retirar el consentimiento otorgado en cualquier momento, sin que ello afecte a la licitud del tratamiento basado en el consentimiento previo a su retirada.<\/p>\r\n<p align=\"justify\">En caso de que sienta vulnerados sus derechos en lo concerniente a la protecci\u00f3n de sus datos personales, especialmente cuando no haya obtenido satisfacci\u00f3n en el ejercicio de sus derechos, puede presentar una reclamaci\u00f3n ante la Autoridad de Control en materia de Protecci\u00f3n de Datos competente a trav\u00e9s de\u00a0su sitio web:\u00a0<a href=\"http:\/\/www.agdp.es\/\" target=\"_blank\" rel=\"noopener\">www.agpd.es<\/a>.<\/p>\r\nCualquier persona tiene derecho a obtener confirmaci\u00f3n sobre si en QUIERES VIAJAR SL\u00a0estamos tratando datos personales que les conciernan, o no.\r\nLas personas interesadas tienen derecho a acceder a sus datos personales, as\u00ed como a\u00a0solicitar la rectificaci\u00f3n de los datos inexactos o, en su caso, solicitar su supresi\u00f3n cuando,\u00a0entre otros motivos, los datos ya no sea necesarios para los fines que fueron recogidos.\r\nEn virtud de lo que establece el RGPD puedes solicitar:\r\n\u2022 Derecho de acceso: puedes pedir informaci\u00f3n de aquellos datos personales que\r\ndispongamos acerca de ti.\r\n\u2022 Derecho de rectificaci\u00f3n: puedes comunicar cualquier cambio en tus datos personales.\r\n\u2022 Derecho de supresi\u00f3n y al olvido: puedes solicitar la eliminaci\u00f3n previo bloqueo de los\u00a0datos personales.\r\n\u2022 Derecho de limitaci\u00f3n al tratamiento: supone la restricci\u00f3n del tratamiento de los datos\u00a0personales.\r\n\u2022 Derecho de oposici\u00f3n: puedes retirar el consentimiento del tratamiento de los datos,\u00a0oponi\u00e9ndose a que se sigan tratando.\r\n\u2022 Derecho a la portabilidad: en algunos casos, puedes pedir una copia de los datos\u00a0personales en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica para su transmisi\u00f3n a\u00a0otro responsable.\r\n\u2022 Derecho a no ser objeto de decisiones individualizadas: puedes solicitar que no se\u00a0tomen decisiones que se basen \u00fanicamente en el tratamiento automatizado, incluyendo la\u00a0elaboraci\u00f3n de per les, que produzca efectos jur\u00eddicos o afecte significativamente al interesado.\r\n\r\nEn algunos casos, se podr\u00e1 rechazar la solicitud si solicitas que se eliminen datos necesarios\u00a0para el cumplimiento de obligaciones legales.\r\nEn determinadas circunstancias, los interesados podr\u00e1n solicitar la limitaci\u00f3n del tratamiento de\u00a0sus datos, en cuyo caso \u00fanicamente los conservaremos para el ejercicio o la defensa de\u00a0reclamaciones. Asimismo, en los supuestos legalmente establecidos, tendr\u00e1 derecho a la\u00a0portabilidad de sus datos personales.\r\nEn determinadas circunstancias y por motivos relacionados con su situaci\u00f3n particular, losinteresados podr\u00e1n oponerse al tratamiento de sus datos. En este caso, QUIERES VIAJAR SL\r\nDejar\u00e1 de tratar los datos, salvo por motivos leg\u00edtimos imperiosos, o el ejercicio o la defensa de\u00a0posibles reclamaciones.\r\nPodr\u00e1 ejercitar materialmente sus derechos de la siguiente forma: enviando un correo\u00a0electr\u00f3nico a info@divertisenvivo.com o en nuestras oficinas sitas en CALLE\u00a0URBANIZACION ITAROA 2 (Centro empresarial Itaroa), 31620 \u2013 Gorraiz (Navarra). Si ha\u00a0otorgado su consentimiento para alguna finalidad concreta, tiene derecho a retirar el\u00a0consentimiento otorgado en cualquier momento, sin que ello afecte a la licitud del tratamiento\u00a0basado en el consentimiento previo a su retirada.\r\nEn caso de que sienta vulnerados sus derechos en lo concerniente a la protecci\u00f3n de sus datos\u00a0personales, especialmente cuando no haya obtenido satisfacci\u00f3n en el ejercicio de sus\u00a0derechos, puede presentar una reclamaci\u00f3n ante la Autoridad de Control en materia de\u00a0Protecci\u00f3n de Datos competente a trav\u00e9s de su sitio web: www.agpd.es.\r\n<h2 align=\"justify\">\u00bfCu\u00e1nto tardamos en contestarte al Ejercicio de Derechos?<\/h2>\r\n<p align=\"justify\">Depende del derecho, pero como m\u00e1ximo en un mes desde tu solicitud, y dos meses si el tema es muy complejo y te notificamos que necesitamos m\u00e1s tiempo<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfQui\u00e9n es el responsable de la exactitud y veracidad de los datos facilitados?<\/h2>\r\n<p align=\"justify\">El usuario es el \u00fanico responsable de la veracidad y correcci\u00f3n de los datos incluidos, exonerando a QUIERES VIAJAR SL de cualquier responsabilidad al respecto. Los usuarios garantizan y responden, en cualquier caso, de la exactitud, vigencia y autenticidad de los datos personales facilitados, y se comprometen a mantenerlos debidamente actualizados. El usuario acepta proporcionar informaci\u00f3n completa y correcta en el formulario de registro o suscripci\u00f3n.\r\nQUIERES VIAJAR SL se reserva el derecho de analizar los servicios contratados que se hubiera celebrado con los usuarios, en caso que los datos que haya facilitado sean falsos, incompletos, inexactos o no est\u00e9n actualizados.\r\nQUIERES VIAJAR SL no responde de la veracidad de las informaciones que no sean de elaboraci\u00f3n propia y de las que se indique otra fuente, por lo que tampoco asume responsabilidad alguna en cuanto a hipot\u00e9ticos perjuicios que pudieran originarse por el uso de dicha informaci\u00f3n.\r\nQUIERES VIAJAR SL se reserva el derecho a actualizar, modificar o eliminar la informaci\u00f3n contenida en sus p\u00e1ginas web pudiendo incluso limitar o no permitir el acceso a dicha informaci\u00f3n. Se exonera a QUIERES VIAJAR SL de responsabilidad ante cualquier da\u00f1o o perjuicio que pudiera sufrir el usuario como consecuencia de errores, defectos u omisiones, en la informaci\u00f3n facilitada por QUIERES VIAJAR SL siempre que proceda de fuentes ajenas a la misma.\r\nAsimismo, el usuario certifica que es mayor de 14 a\u00f1os y que posee la capacidad legal necesaria para la prestaci\u00f3n del consentimiento en cuanto al tratamiento de sus datos de car\u00e1cter personal.<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfC\u00f3mo tratamos los datos personales de los menores de edad?<\/h2>\r\n<p align=\"justify\">En principio nuestros servicios no van dirigidos espec\u00edficamente a menos de edad. Sin embargo, en el supuesto de que alguno de ellos se dirija a menores de catorce a\u00f1os, de conformidad con el art\u00edculo 8 del RGPD y el art\u00edculo 7 de la LO 3\/2018, de 5 de diciembre (LOPDGDD), QUIERES VIAJAR SL exigir\u00e1 el consentimiento v\u00e1lido, libre, inequ\u00edvoco, espec\u00edfico e informado de sus tutores legales para tratar los datos personales de los menores. En este caso, se exigir\u00e1 el DNI u otra forma de identificaci\u00f3n de quien preste el consentimiento.<\/p>\r\n<p align=\"justify\">En el caso de mayores de catorce a\u00f1os podr\u00e1 procederse al tratamiento de los datos con el consentimiento del usuario, exceptuando aquellos casos en los que la Ley exija la asistencia de los titulares de la patria potestad o tutela.<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfQu\u00e9 medidas de seguridad aplicamos para proteger tus datos personales?<\/h2>\r\n<p align=\"justify\">QUIERES VIAJAR SL ha adoptado los niveles de seguridad de protecci\u00f3n de los Datos Personales legalmente requeridos, y procura instalar aquellos otros medios y medidas t\u00e9cnicas adicionales a su alcance para evitar la p\u00e9rdida, mal uso, alteraci\u00f3n, acceso no autorizado y robo de los Datos Personales facilitados a QUIERES VIAJAR SL<\/p>\r\n<p align=\"justify\">QUIERES VIAJAR SL no es responsable de hipot\u00e9ticos da\u00f1os o perjuicios que se pudieran derivar de interferencias, omisiones, interrupciones, virus inform\u00e1ticos, aver\u00edas telef\u00f3nicas o desconexiones en el funcionamiento operativo de este sistema electr\u00f3nico, motivadas por causas ajenas a QUIERES VIAJAR SL; de retrasos o bloqueos en el uso del presente sistema electr\u00f3nico causados por deficiencias o sobrecargas de l\u00edneas telef\u00f3nicas o sobrecargas en el Centro de Procesos de Datos, en el sistema de Internet o en otros sistemas electr\u00f3nicos, as\u00ed como de da\u00f1os que puedan ser causados por terceras personas mediante intromisiones ileg\u00edtimas fuera del control de QUIERES VIAJAR SL. Ello no obstante, el usuario debe ser consciente de que las medidas de seguridad en Internet no son inexpugnables.<\/p>\r\n\r\n<h2 align=\"justify\">Enlaces a otros sitios web<\/h2>\r\n<p align=\"justify\">En el sitio web https:\/\/www.divertisenvivo.com\/puede haber enlaces a otras p\u00e1ginas web. Al clicar en uno de estos enlaces y acceder a un sitio web externo, la visita estar\u00e1 sujeta a la pol\u00edtica de privacidad de dicho sitio web, quedando QUIERES VIAJAR SL desvinculada de cualquier tipo de responsabilidad acerca de su pol\u00edtica de privacidad<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfC\u00f3mo utilizamos las cookies?<\/h2>\r\n<p align=\"justify\">El sitio web y las RRSS de QUIERES VIAJAR SL utilizan cookies, a los efectos de optimizar y\u00a0personalizar su navegaci\u00f3n por el mismo. Las cookies son cheros f\u00edsicos de informaci\u00f3n que se\u00a0alojan en el propio terminal del usuario, la informaci\u00f3n recogida mediante las cookies sirve para\u00a0facilitar la navegaci\u00f3n del usuario por el portal y optimizar la experiencia de navegaci\u00f3n. Los\u00a0datos recopilados mediante las cookies pueden ser compartidos con los creadores de las\u00a0mismas, pero en ning\u00fan caso la informaci\u00f3n obtenida por las mismas ser\u00e1 asociada a datos\u00a0personales ni a datos que puedan identificar al usuario.\r\nSin embargo, si el usuario no desea que se instalen cookies en su disco duro, tiene la\u00a0posibilidad de configurar el navegador de tal modo que impida la instalaci\u00f3n de estos archivos.\u00a0Para obtener m\u00e1s informaci\u00f3n consulte nuestra Pol\u00edtica de Cookies\u00a0https:\/\/www.divertisenvivo.com\/.<\/p>\r\n\r\n<h2 align=\"justify\">\u00bfPuede modificarse la pol\u00edtica de privacidad?<\/h2>\r\n<p align=\"justify\">Esta pol\u00edtica de privacidad puede modificarse. Te recomendamos que revises la pol\u00edtica de privacidad con cierta periodicidad.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"evf-honeypot-container evf-field-hp\"><label for=\"evf-169945-field-hp\" class=\"evf-field-label\">Message<\/label><input type=\"text\" name=\"everest_forms[hp]\" id=\"evf-169945-field-hp\" class=\"input-text\"><\/div><div class=\"evf-submit-container \" ><input type=\"hidden\" name=\"everest_forms[id]\" value=\"169945\"><input type=\"hidden\" name=\"everest_forms[author]\" value=\"1\"><button type='submit' name='everest_forms[submit]' class='everest-forms-submit-button button evf-submit ' id='evf-submit-169945' value='evf-submit' data-process-text=\"Enviando...\" conditional_rules='&quot;&quot;' conditional_id='evf-submit-169945'  id=\"evf-submit-169945\" aria-live=\"assertive\">Enviar<\/button><\/div><\/form><\/div><!-- .evf-container --><\/div> <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4952c903 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"4952c903\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6488fae9 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"6488fae9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-71db9da\" href=\"https:\/\/www.facebook.com\/divertisenvivo\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-9767c4a\" href=\"https:\/\/www.instagram.com\/divertisenvivo\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-f7a3d0f\" href=\"https:\/\/es.linkedin.com\/company\/divertis-en-vivo-viajesaconciertosyfestivales\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mundial 2026 &#8211; Viajes a USA, M\u00e9xico y Canada El Mundial de F\u00fatbol 2026 se disputar\u00e1 en 3 pa\u00edses como<\/p>","protected":false},"author":1,"featured_media":172217,"parent":1225,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-172200","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viajes al Mundial 2026 USA, M\u00e9xico y Canada<\/title>\n<meta name=\"description\" content=\"Viajes al Mundial 2026 de USA, M\u00e9xico y Canada. \u00bfQuieres que te ayudemos en la b\u00fasqueda de vuelos, traslados, hoteles y entradas?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viajes al Mundial 2026 USA, M\u00e9xico y Canada\" \/>\n<meta property=\"og:description\" content=\"Viajes al Mundial 2026 de USA, M\u00e9xico y Canada. \u00bfQuieres que te ayudemos en la b\u00fasqueda de vuelos, traslados, hoteles y entradas?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Divertis en Vivo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/divertisenvivo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T14:06:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.divertisenvivo.com\/wp-content\/uploads\/2026\/02\/Mundial-de-futbol-2026-1920-x-800-px-1024x427.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@divertisenvivo\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/\",\"url\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/\",\"name\":\"Viajes al Mundial 2026 USA, M\u00e9xico y Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.divertisenvivo.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Mundial-de-futbol-2026-1920-x-800-px.png?fit=1920%2C800&ssl=1\",\"datePublished\":\"2026-02-11T13:29:45+00:00\",\"dateModified\":\"2026-02-11T14:06:39+00:00\",\"description\":\"Viajes al Mundial 2026 de USA, M\u00e9xico y Canada. \u00bfQuieres que te ayudemos en la b\u00fasqueda de vuelos, traslados, hoteles y entradas?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.divertisenvivo.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Mundial-de-futbol-2026-1920-x-800-px.png?fit=1920%2C800&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.divertisenvivo.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Mundial-de-futbol-2026-1920-x-800-px.png?fit=1920%2C800&ssl=1\",\"width\":1920,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/mundial2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.divertisenvivo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FUTBOL\",\"item\":\"https:\\\/\\\/www.divertisenvivo.com\\\/futbol-en-vivo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mundial 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/\",\"name\":\"Divertis en vivo - Viajes a eventos musicales, deportivos y culturales\",\"description\":\"Desde 2007, somos tu agencia de viajes para disfrutar de tus eventos deportivos (Rugby, Futbol) y de tus eventos musicales (festivales y conciertos)\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/#organization\",\"name\":\"Quieres Viajar S.L.\",\"url\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.divertisenvivo.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-e1610098969786.png\",\"contentUrl\":\"https:\\\/\\\/www.divertisenvivo.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/logo-e1610098969786.png\",\"width\":200,\"height\":139,\"caption\":\"Quieres Viajar S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.divertisenvivo.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/divertisenvivo\",\"https:\\\/\\\/x.com\\\/divertisenvivo\",\"https:\\\/\\\/www.instagram.com\\\/divertisenvivo\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/divertis-en-vivo-viajesaconciertosyfestivales\\\/?viewAsMember=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viajes al Mundial 2026 USA, M\u00e9xico y Canada","description":"Viajes al Mundial 2026 de USA, M\u00e9xico y Canada. \u00bfQuieres que te ayudemos en la b\u00fasqueda de vuelos, traslados, hoteles y entradas?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/","og_locale":"en_US","og_type":"article","og_title":"Viajes al Mundial 2026 USA, M\u00e9xico y Canada","og_description":"Viajes al Mundial 2026 de USA, M\u00e9xico y Canada. \u00bfQuieres que te ayudemos en la b\u00fasqueda de vuelos, traslados, hoteles y entradas?","og_url":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/","og_site_name":"Divertis en Vivo","article_publisher":"https:\/\/www.facebook.com\/divertisenvivo","article_modified_time":"2026-02-11T14:06:39+00:00","og_image":[{"width":1024,"height":427,"url":"https:\/\/www.divertisenvivo.com\/wp-content\/uploads\/2026\/02\/Mundial-de-futbol-2026-1920-x-800-px-1024x427.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@divertisenvivo","twitter_misc":{"Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/","url":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/","name":"Viajes al Mundial 2026 USA, M\u00e9xico y Canada","isPartOf":{"@id":"https:\/\/www.divertisenvivo.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/#primaryimage"},"image":{"@id":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.divertisenvivo.com\/wp-content\/uploads\/2026\/02\/Mundial-de-futbol-2026-1920-x-800-px.png?fit=1920%2C800&ssl=1","datePublished":"2026-02-11T13:29:45+00:00","dateModified":"2026-02-11T14:06:39+00:00","description":"Viajes al Mundial 2026 de USA, M\u00e9xico y Canada. \u00bfQuieres que te ayudemos en la b\u00fasqueda de vuelos, traslados, hoteles y entradas?","breadcrumb":{"@id":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/#primaryimage","url":"https:\/\/i0.wp.com\/www.divertisenvivo.com\/wp-content\/uploads\/2026\/02\/Mundial-de-futbol-2026-1920-x-800-px.png?fit=1920%2C800&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.divertisenvivo.com\/wp-content\/uploads\/2026\/02\/Mundial-de-futbol-2026-1920-x-800-px.png?fit=1920%2C800&ssl=1","width":1920,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.divertisenvivo.com\/eu\/mundial2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.divertisenvivo.com\/"},{"@type":"ListItem","position":2,"name":"FUTBOL","item":"https:\/\/www.divertisenvivo.com\/futbol-en-vivo\/"},{"@type":"ListItem","position":3,"name":"Mundial 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.divertisenvivo.com\/eu\/#website","url":"https:\/\/www.divertisenvivo.com\/eu\/","name":"Divertis en vivo - Viajes a eventos musicales, deportivos y culturales","description":"2007 urtetik aurrera kirol eta musika ekiteldieetara eramaten zaitugun bidaia agentzia gara: rugby, futbola, festibal eta kontzertuez goza itzazu gure eskuz.","publisher":{"@id":"https:\/\/www.divertisenvivo.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.divertisenvivo.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.divertisenvivo.com\/eu\/#organization","name":"Quieres Viajar S.L.","url":"https:\/\/www.divertisenvivo.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.divertisenvivo.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.divertisenvivo.com\/wp-content\/uploads\/2021\/01\/logo-e1610098969786.png","contentUrl":"https:\/\/www.divertisenvivo.com\/wp-content\/uploads\/2021\/01\/logo-e1610098969786.png","width":200,"height":139,"caption":"Quieres Viajar S.L."},"image":{"@id":"https:\/\/www.divertisenvivo.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/divertisenvivo","https:\/\/x.com\/divertisenvivo","https:\/\/www.instagram.com\/divertisenvivo\/","https:\/\/www.linkedin.com\/company\/divertis-en-vivo-viajesaconciertosyfestivales\/?viewAsMember=true"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/pages\/172200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/comments?post=172200"}],"version-history":[{"count":12,"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/pages\/172200\/revisions"}],"predecessor-version":[{"id":172221,"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/pages\/172200\/revisions\/172221"}],"up":[{"embeddable":true,"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/pages\/1225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/media\/172217"}],"wp:attachment":[{"href":"https:\/\/www.divertisenvivo.com\/eu\/wp-json\/wp\/v2\/media?parent=172200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}